{"id":7536,"date":"2020-03-26T18:06:55","date_gmt":"2020-03-26T17:06:55","guid":{"rendered":"https:\/\/www.akademie-solitude.de\/event\/performancereihe-zur-ausstellung-around-analogies\/"},"modified":"2020-08-12T09:47:40","modified_gmt":"2020-08-12T07:47:40","slug":"performancereihe-zur-ausstellung-around-analogies","status":"publish","type":"event","link":"https:\/\/www.akademie-solitude.de\/de\/event\/performancereihe-zur-ausstellung-around-analogies\/","title":{"rendered":"PERFORMANCEREIHE ZUR AUSSTELLUNG \u00bbAROUND ANALOGIES\u00ab"},"content":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","categories":[29,30],"class_list":["post-7536","event","type-event","status-publish","hentry","category-lesung","category-performance"],"acf":{"bgcolor":"","bgcolor_custom":"","custom_color_css_variable":"","content_type":null,"intro_preview_headline":"","intro_preview_txt":"<p>Am 21. Februar startet R. Armstrongs Performancereihe im Rahmen der Gruppenausstellung <em>Around Analogies<\/em> an der Akademie Schloss Solitude. Als Teil ihrer Installation <em>The Said Woman<\/em> wird die K\u00fcnstlerin aus dem Gerichtsprotokoll des Prozesses gegen Jeanne D'Arc lesen. Die Lesungen werden am <strong>21. 22., 24., 27. Februar<\/strong> <strong>und 1. M\u00e4rz<\/strong> um jeweils 14 Uhr stattfinden.<br><\/p>","intro_preview_img":8262,"event_id_old":"3706","event_subtitle":"","event_date":"2015-02-21 00:00:00","event_date_end":"2015-03-01 14:00:00","event_location":[{"event_location_name":"Akademie Schloss Solitude","event_location_link":""}],"event_programme":"","event_taxonomy_category":[29,30],"event_practice_field":false,"event_opening":"","event_opening_times":"","event_additional_info":"","event_txt_old":"<p>Vom 21. Februar bis 25. M\u00e4rz 1431 wurde der erste Prozess gegen Jeanne d\u2019Arc abgehalten. Zun\u00e4chst im Ankleidezimmer der Burg Bouvreuil in Rouen, sp\u00e4ter in einer Kammer der Burg, die als ihr Gef\u00e4ngnis genutzt wurde. Die vielleicht bedeutsamste Person in diesem Raum, abgesehen von Jeanne selbst, war Guillaume Manchon, der Gerichtsnotar. Er schrieb das Gerichtsprotokoll in franz\u00f6sischer Sprache und \u00fcbersetzte es sp\u00e4ter ins Lateinische. Drei der f\u00fcnf bekannten handschriftlichen Kopien stammen von ihm. The Said Woman ist eine Erkundung des Dokuments an sich und untersucht die darin eingebetteten komplexen \u00dcberlagerungen von \u00dcbersetzung und Transkription. Dies geschieht in Abgrenzung zu den zahlreichen Mythen, von welchen das Dokument und seine Geschichte umgeben ist.<\/p><p>Am <strong>21., 22., 24., 27. Februar und 1. M\u00e4rz<\/strong> wird das Gerichtsdokument des jeweiligen Tages in der englischen \u00dcbersetzung vorgelesen. Die Lesung ist Teil der Gruppenausstellung <em><a href=\"https:\/\/www.akademie-solitude.de\/de\/veranstaltungen\/ausstellungseroeffnungen~no3699\/\" target=\"_blank\" data-cke-saved-href=\"https:\/\/www.akademie-solitude.de\/de\/veranstaltungen\/ausstellungseroeffnungen~no3699\/\">Around Analogies<\/a><\/em> und wird am jeweiligen Verhandlungstag um 14 Uhr in der N\u00e4he der Installation<em> The Said Woman<\/em> in der Akademie Schloss Solitude stattfinden. Wenn Sie n\u00e4here Informationen zu den Ank\u00fcndigungen am jeweiligen Morgen der Gerichtsverhandlung erhalten m\u00f6chten, senden Sie eine <a href=\"mailto:rstonestreet@gmail.com?subject=\u00bbjudges\u00ab\" data-cke-saved-href=\"mailto:rstonestreet@gmail.com?subject=\u00bbjudges\u00ab\">E-Mail<\/a> mit dem Betreff \u00bbjudges\u00ab an die K\u00fcnstlerin.<br><\/p><p>Die Onlineversion des Projekts ist <a href=\"http:\/\/rarmstrongworks.com\/category\/thesaidwoman\" target=\"_blank\" data-cke-saved-href=\"http:\/\/rarmstrongworks.com\/category\/thesaidwoman\">hier<\/a> einzusehen.<br><\/p>","event_more_events":"","related_posts_event":""},"_links":{"self":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/event\/7536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/users\/1"}],"acf:term":[{"embeddable":true,"taxonomy":"category","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/categories\/30"},{"embeddable":true,"taxonomy":"category","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/categories\/29"}],"wp:attachment":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/media?parent=7536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/categories?post=7536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}