{"id":6748,"date":"2020-03-26T14:49:15","date_gmt":"2020-03-26T13:49:15","guid":{"rendered":"https:\/\/www.akademie-solitude.de\/person\/ana-matnadze\/"},"modified":"2020-08-12T17:30:45","modified_gmt":"2020-08-12T15:30:45","slug":"ana-matnadze","status":"publish","type":"person","link":"https:\/\/www.akademie-solitude.de\/de\/person\/ana-matnadze\/","title":{"rendered":"Ana  Matnadze"},"content":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"person_type":[57],"program":[],"practice_field":[112],"year_generation":[98,99,100],"class_list":["post-6748","person","type-person","status-publish","hentry","person_type-stipendiatinnen","practice_field-schach","year_generation-98","year_generation-99","year_generation-100"],"acf":{"person_id__old":"3583","person_name":{"person_name":"Ana","person_middlename":"","person_surname":"Matnadze"},"person_metadata":"","person_position":[57],"person_job":"","person_txt":"<p>Geboren 1983 in Telawi\/Georgien.<\/p>\n<p>Ann Matnadze studierte International Journalism an der Ivane Javakhishvili Tbilisi State University (1999\u20132005) in Georgien. Neben ihrer Karriere als Schachspielerin (Gro\u00dfmeisterin), arbeitet sie als Referentin f\u00fcr \u00d6ffentlichkeitsarbeit beim angesehenen Magistral Casino de Barcelona in Spanien. Ihre Mutter brachte ihr im Alter von vier Jahren das Schachspielen bei. Seitdem hat sie viele internationale Titel gewonnen, sie war Weltmeisterin in den Klassen U10 und U14 und einige Male Europameisterin in verschiedenen Altersklassen, sowie Gewinnerin zahlreicher Team- und Einzelwettbewerbe. Bei der Schacholympiade 2012 in Istanbul\/T\u00fcrkei repr\u00e4sentierte sie Spanien am ersten Brett. Ferner nahm sie an verschiedenen Wohlt\u00e4tigkeitsturnieren teil, wie einem Schachturnier zur Unterst\u00fctzung von Flutopfern in Westgeorgien in Tbilisi\/Georgien (2005), dem Charity Turnier Chess Against Drugs (2006) in Tbilisi, dem Austauschprogramm <em>Chess and Friendship<\/em> (2006) in Georgien und Katalanien\/Spanien, dem Austauschprogramm<em> Chess for Peace and Understanding <\/em>(2007) in Georgien und Katalanien sowie am Schachprojekt <em>We Play For Peace <\/em>(2009) in Las Palmas de Gran Canaria\/Spanien.<\/p>\n<p class=\"MsoNormal\">Zu ihren zahlreichen Auszeichnungen geh\u00f6rt \u00bbGrantee of the Foundation\u00ab des Pr\u00e4sidenten von Georgien (1998, 2003) und ein Stipendium (2001), welches ebenfalls vom Pr\u00e4sidenten Georgiens eingef\u00fchrt wurde.<br>\nAnn Matnadze widmet ihre Zeit und ihre M\u00fche kontinuierlich der Unterst\u00fctzung von weltweiten Wohlt\u00e4tigkeitsorganisationen. Seit 2005 ist sie Pr\u00e4sidentin der internationalen Wohlt\u00e4tigkeitsbewegung <em>Chess \u2013 a Peace Ambassador<\/em>, einer gemeinn\u00fctzigen Organisation, die bereits einige internationale Veranstaltungen, wie das Austauschprogramm zwischen Georgien und Katalanien (Spanien), organisiert hat.<\/p>\n<p><span bold\"=\"\" lang=\"DE\">Sie lebt zurzeit in Barcelona und repr\u00e4sentiert Spanien bei internationalen Turnieren.<\/span>\u00a0<\/p>","person_txt_short":"","person_img":"","person_website":"","person_links":null,"person_year":[98,99,100],"person_residencies":[{"person_stay_from":"20131201","person_stay_to":"20140531"}],"person_residency_sort_stay_from":null,"person_residency_sort_stay_to":null,"person_practice_field":[112],"person_program":false,"person_locations":[{"person_city":"Barcelona","person_country":"Spanien"}],"person_country":"","related_posts_event":"","related_posts_news":"","related_posts_post":null,"related_posts_schlosspost":null,"person_fellow_juror_relation":[6672]},"_links":{"self":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/person\/6748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/types\/person"}],"author":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/users\/1"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/person\/6672"}],"acf:term":[{"embeddable":true,"taxonomy":"practice_field","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/practice_field\/112"},{"embeddable":true,"taxonomy":"year_generation","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/year_generation\/100"},{"embeddable":true,"taxonomy":"year_generation","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/year_generation\/99"},{"embeddable":true,"taxonomy":"year_generation","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/year_generation\/98"},{"embeddable":true,"taxonomy":"person_type","href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/person_type\/57"}],"wp:attachment":[{"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/media?parent=6748"}],"wp:term":[{"taxonomy":"person_type","embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/person_type?post=6748"},{"taxonomy":"program","embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/program?post=6748"},{"taxonomy":"practice_field","embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/practice_field?post=6748"},{"taxonomy":"year_generation","embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/de\/wp-json\/wp\/v2\/year_generation?post=6748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}