{"id":46540,"date":"2026-06-16T14:53:05","date_gmt":"2026-06-16T12:53:05","guid":{"rendered":"https:\/\/www.akademie-solitude.de\/scope\/archiv\/"},"modified":"2026-09-01T18:16:19","modified_gmt":"2026-09-01T16:16:19","slug":"archiv","status":"publish","type":"page","link":"https:\/\/www.akademie-solitude.de\/en\/scope\/archiv\/","title":{"rendered":"Archiv"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":46535,"menu_order":56,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-46540","page","type-page","status-publish","hentry"],"acf":{"bgcolor":"","bgcolor_custom":"","custom_color_css_variable":"","content_type":[{"acf_fc_layout":"content_txt","_acfe_flexible_layout_title":null,"bgcolor":"","bgcolor_custom":"","layout_col_size":8,"txt_cols":"is-1-txtcol","txt":"<p class=\"p1\">\r\nThe SCOPE archive brings together past projects and topics from the programmatic focus areas of <em>art, science &amp; business<\/em>, <em>Digital Cultures<\/em>, as well as long-term projects from previous years.<\/p>\r\n\r\n<h3 style=\"text-align: center;\">Programs<\/h3>"},{"acf_fc_layout":"content_teaser","_acfe_flexible_layout_title":null,"teaser_elements":[{"teaser_bgcolor":"","teaser_outline":true,"teaser_border":["has-border-top-black","has-border-right-black","has-border-bottom-black","has-border-left-black"],"teaser_type":"teaser_post","teaser_preview":["preview_txt"],"teaser_preview_img_style":false,"teaser_obj_type":"teaser_post","teaser_obj_el":20799,"teaser_taxonomy_el":null,"teaser_headline":"2002 - 2026","teaser_person_current":false,"teaser_person_current_juror":false,"teaser_person_current_employee":false,"post_taxonomies_person_type":[],"post_taxonomies_program":[],"post_taxonomies_year_generation":[],"post_taxonomies_practice_field":[],"teaser_btntxt":"more information"},{"teaser_bgcolor":"","teaser_outline":true,"teaser_border":["has-border-top-black","has-border-right-black","has-border-bottom-black"],"teaser_type":"teaser_post","teaser_preview":["preview_txt"],"teaser_preview_img_style":false,"teaser_obj_type":"teaser_post","teaser_obj_el":21248,"teaser_taxonomy_el":null,"teaser_headline":"2016 - 2026","teaser_person_current":false,"teaser_person_current_juror":false,"teaser_person_current_employee":false,"post_taxonomies_person_type":[],"post_taxonomies_program":[],"post_taxonomies_year_generation":[],"post_taxonomies_practice_field":[],"teaser_btntxt":"more information"}]},{"acf_fc_layout":"content_txt","_acfe_flexible_layout_title":null,"bgcolor":"","bgcolor_custom":"","layout_col_size":8,"txt_cols":"is-1-txtcol","txt":"<h3 style=\"text-align: center;\">Projects<\/h3>"},{"acf_fc_layout":"content_teaser","_acfe_flexible_layout_title":null,"teaser_elements":[{"teaser_bgcolor":"","teaser_outline":true,"teaser_border":["has-border-top-black","has-border-right-black","has-border-bottom-black","has-border-left-black"],"teaser_type":"teaser_post","teaser_preview":["preview_txt"],"teaser_preview_img_style":false,"teaser_obj_type":"teaser_post","teaser_obj_el":21050,"teaser_taxonomy_el":null,"teaser_headline":"2020 - 2021","teaser_person_current":false,"teaser_person_current_juror":false,"teaser_person_current_employee":false,"post_taxonomies_person_type":[],"post_taxonomies_program":[],"post_taxonomies_year_generation":[],"post_taxonomies_practice_field":[],"teaser_btntxt":"more information"},{"teaser_bgcolor":"","teaser_outline":true,"teaser_border":["has-border-top-black","has-border-right-black","has-border-bottom-black"],"teaser_type":"teaser_post","teaser_preview":["preview_txt"],"teaser_preview_img_style":false,"teaser_obj_type":"teaser_post","teaser_obj_el":22666,"teaser_taxonomy_el":null,"teaser_headline":"2021 - 2022","teaser_person_current":false,"teaser_person_current_juror":false,"teaser_person_current_employee":false,"post_taxonomies_person_type":[],"post_taxonomies_program":[],"post_taxonomies_year_generation":[],"post_taxonomies_practice_field":[],"teaser_btntxt":"more information"}]}]},"_links":{"self":[{"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/pages\/46540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/comments?post=46540"}],"version-history":[{"count":3,"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/pages\/46540\/revisions"}],"predecessor-version":[{"id":46545,"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/pages\/46540\/revisions\/46545"}],"up":[{"embeddable":true,"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/pages\/46535"}],"wp:attachment":[{"href":"https:\/\/www.akademie-solitude.de\/en\/wp-json\/wp\/v2\/media?parent=46540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}